{"id":3434,"date":"2025-03-30T08:12:42","date_gmt":"2025-03-30T08:12:42","guid":{"rendered":"https:\/\/formosatrail.com\/?page_id=3434"},"modified":"2026-04-21T06:14:28","modified_gmt":"2026-04-20T22:14:28","slug":"transportation","status":"publish","type":"page","link":"https:\/\/formosatrail.com\/zh\/transportation\/","title":{"rendered":"\u5927\u773e\u904b\u8f38\u5de5\u5177"},"content":{"rendered":"<style>.kb-row-layout-id3434_5fad07-68 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id3434_5fad07-68 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id3434_5fad07-68 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:700px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);min-height:60vh;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3434_5fad07-68{background-image:url('https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/04\/FT-hike-10k-06.jpg');background-size:cover;background-position:54% 47%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id3434_5fad07-68 > .kt-row-layout-overlay{opacity:0.60;background-color:var(--global-palette3, #1A202C);mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id3434_5fad07-68 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_5fad07-68 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_5fad07-68 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column3434_b5c6d7-d8 > .kt-inside-inner-col,.kadence-column3434_b5c6d7-d8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_b5c6d7-d8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_b5c6d7-d8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_b5c6d7-d8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_b5c6d7-d8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_b5c6d7-d8{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_b5c6d7-d8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_b5c6d7-d8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_b5c6d7-d8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_c258a8-d1, .wp-block-kadence-advancedheading.kt-adv-heading3434_c258a8-d1[data-kb-block=\"kb-adv-heading3434_c258a8-d1\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_c258a8-d1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_c258a8-d1[data-kb-block=\"kb-adv-heading3434_c258a8-d1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3434_c258a8-d1 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_c258a8-d1\">\u5927\u773e\u904b\u8f38\u5de5\u5177<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_9f7dd1-de, .wp-block-kadence-advancedheading.kt-adv-heading3434_9f7dd1-de[data-kb-block=\"kb-adv-heading3434_9f7dd1-de\"]{text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_9f7dd1-de mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_9f7dd1-de[data-kb-block=\"kb-adv-heading3434_9f7dd1-de\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_9f7dd1-de wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_9f7dd1-de\">Be Green \u2013 Take bus \ud83d\ude8c\ud83c\udf3f<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3434_6731cd-7d{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id3434_6731cd-7d > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id3434_6731cd-7d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id3434_6731cd-7d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:1000px;margin-left:auto;margin-right:auto;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3434_6731cd-7d > .kt-row-layout-overlay{opacity:0.00;}@media all and (max-width: 1024px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3434_6731cd-7d{margin-top:30px;margin-bottom:0px;}}@media all and (max-width: 1024px){.kb-row-layout-id3434_6731cd-7d > .kt-row-column-wrap{padding-top:0px;padding-right:20px;padding-bottom:0px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_6731cd-7d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_6731cd-7d alignfull has-theme-palette5-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column3434_cb8594-43 > .kt-inside-inner-col{display:flex;}.kadence-column3434_cb8594-43 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-lg, 3rem);}.kadence-column3434_cb8594-43 > .kt-inside-inner-col{box-shadow:20px 20px 80px 0px rgba(43, 35, 34, 0.27);border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}.kadence-column3434_cb8594-43 > .kt-inside-inner-col,.kadence-column3434_cb8594-43 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column3434_cb8594-43 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_cb8594-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3434_cb8594-43 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_cb8594-43{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_cb8594-43{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_cb8594-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3434_cb8594-43 > .kt-inside-inner-col{background-color:var(--global-palette4, #2D3748);}.kadence-column3434_cb8594-43 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_cb8594-43{z-index:100;position:relative;}.kadence-column3434_cb8594-43, .kt-inside-inner-col > .kadence-column3434_cb8594-43:not(.specificity){margin-top:-110px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column3434_cb8594-43 > .kt-inside-inner-col{border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_cb8594-43{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_cb8594-43{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_cb8594-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3434_cb8594-43, .kt-inside-inner-col > .kadence-column3434_cb8594-43:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column3434_cb8594-43 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column3434_cb8594-43{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_cb8594-43{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_cb8594-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_cb8594-43 border-stl\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3434_4b8d81-1a > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id3434_4b8d81-1a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id3434_4b8d81-1a > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1250px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((40px * 1 )\/2)))minmax(0, calc(75% - ((40px * 1 )\/2)));}.kb-row-layout-id3434_4b8d81-1a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_4b8d81-1a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_4b8d81-1a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_4b8d81-1a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column3434_8723db-fc > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column3434_8723db-fc > .kt-inside-inner-col,.kadence-column3434_8723db-fc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_8723db-fc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_8723db-fc > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_8723db-fc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_8723db-fc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_8723db-fc{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_8723db-fc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_8723db-fc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_8723db-fc inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image3434_4bf0d7-a8 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3434_4bf0d7-a8 size-large kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-683x1024.jpg\" alt=\"Dynamic cityscape with a red bus in motion, set against a modern building facade.\" class=\"kb-img wp-image-3728\" srcset=\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-683x1024.jpg 683w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-200x300.jpg 200w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-768x1152.jpg 768w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-1024x1536.jpg 1024w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-1365x2048.jpg 1365w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{display:flex;}.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column3434_2ca686-e6 > .kt-inside-inner-col,.kadence-column3434_2ca686-e6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3434_2ca686-e6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_2ca686-e6{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_2ca686-e6{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3434_2ca686-e6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_2ca686-e6{position:relative;}.kadence-column3434_2ca686-e6, .kt-inside-inner-col > .kadence-column3434_2ca686-e6:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:20px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_2ca686-e6{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_2ca686-e6{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_2ca686-e6{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_2ca686-e6{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3434_2ca686-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3434_2ca686-e6, .kt-inside-inner-col > .kadence-column3434_2ca686-e6:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_2ca686-e6 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_04a4df-60, .wp-block-kadence-advancedheading.kt-adv-heading3434_04a4df-60[data-kb-block=\"kb-adv-heading3434_04a4df-60\"]{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.2em;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading3434_04a4df-60 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_04a4df-60[data-kb-block=\"kb-adv-heading3434_04a4df-60\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3434_04a4df-60, .wp-block-kadence-advancedheading.kt-adv-heading3434_04a4df-60[data-kb-block=\"kb-adv-heading3434_04a4df-60\"]{text-align:center!important;}}<\/style>\n<h3 class=\"kt-adv-heading3434_04a4df-60 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_04a4df-60\">We took care about everything!<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_aaeb04-08, .wp-block-kadence-advancedheading.kt-adv-heading3434_aaeb04-08[data-kb-block=\"kb-adv-heading3434_aaeb04-08\"]{margin-top:0px;margin-right:0px;margin-bottom:20px;margin-left:0px;line-height:1.4em;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_aaeb04-08 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_aaeb04-08[data-kb-block=\"kb-adv-heading3434_aaeb04-08\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3434_aaeb04-08, .wp-block-kadence-advancedheading.kt-adv-heading3434_aaeb04-08[data-kb-block=\"kb-adv-heading3434_aaeb04-08\"]{text-align:center!important;}}<\/style>\n<p class=\"kt-adv-heading3434_aaeb04-08 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_aaeb04-08\">\u4e09\u5929\u5728\u53f0\u7063\u4e2d\u90e8 - \u57d4\u91cc<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns3434_90ea2f-8d{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3434_90ea2f-8d .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn.kb-btns3434_90ea2f-8d{justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns3434_90ea2f-8d{justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3434_90ea2f-8d\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3434_8c7ea7-44.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3434_8c7ea7-44.kb-button{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style><a class=\"kb-button kt-button button kb-btn3434_8c7ea7-44 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/formosatrail.com\/zh\/registration\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">\u5728\u5831\u540d\u6642\u9810\u8a02\u63a5\u99c1\u8eca<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3434_a8b050-3a > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id3434_a8b050-3a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id3434_a8b050-3a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3434_a8b050-3a > .kt-row-layout-overlay{opacity:0.85;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id3434_a8b050-3a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_a8b050-3a > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_a8b050-3a alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom kb-theme-content-width\">\n<style>.kadence-column3434_4faac3-bf > .kt-inside-inner-col{display:flex;}.kadence-column3434_4faac3-bf > .kt-inside-inner-col,.kadence-column3434_4faac3-bf > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_4faac3-bf > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_4faac3-bf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_4faac3-bf > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_4faac3-bf{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_4faac3-bf{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_4faac3-bf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_4faac3-bf > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_4faac3-bf{text-align:left;}.kadence-column3434_4faac3-bf{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_4faac3-bf{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_4faac3-bf{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_4faac3-bf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column3434_4faac3-bf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_4faac3-bf{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_4faac3-bf{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_4faac3-bf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_4faac3-bf > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_4faac3-bf kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_a8fd53-11, .wp-block-kadence-advancedheading.kt-adv-heading3434_a8fd53-11[data-kb-block=\"kb-adv-heading3434_a8fd53-11\"]{font-size:32px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_a8fd53-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_a8fd53-11[data-kb-block=\"kb-adv-heading3434_a8fd53-11\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3434_a8fd53-11 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading3434_a8fd53-11\">\u524d\u4f86\u65b9\u5f0f<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_552311-ee > .kt-inside-inner-col{display:flex;}.kadence-column3434_552311-ee > .kt-inside-inner-col,.kadence-column3434_552311-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_552311-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_552311-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_552311-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_552311-ee{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_552311-ee{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_552311-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_552311-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_552311-ee{text-align:left;}.kadence-column3434_552311-ee{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_552311-ee{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_552311-ee{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_552311-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column3434_552311-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_552311-ee{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_552311-ee{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_552311-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_552311-ee > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_552311-ee kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id3434_e8466b-d9 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);}.kt-accordion-id3434_e8466b-d9 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:rgba(255,255,255,0);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette7, #EDF2F7);font-size:18px;line-height:1.2;font-weight:600;text-transform:none;color:var(--global-palette3, #1A202C);padding-top:15px;padding-right:20px;padding-bottom:15px;padding-left:0px;}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_e8466b-d9 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette9, #ffffff);background:var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette5, #4A5568);}.kt-accordion-id3434_e8466b-d9 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e8466b-d9:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.kt-accordion-id3434_e8466b-d9 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;}}@media all and (max-width: 1024px){.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_e8466b-d9 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 1024px){.kt-accordion-id3434_e8466b-d9 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-accordion-id3434_e8466b-d9 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3434_e8466b-d9 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;}.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_e8466b-d9 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_e8466b-d9 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_e8466b-d9 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3434_e8466b-d9 kt-accordion-has-12-panes kt-active-pane-8 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"true\" data-start-open=\"8\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-9 kt-pane3434_9d111a-21\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>\u53f0\u5317\u8eca\u7ad9\u6771 3 \u9580\u5230\u6d3b\u52d5\u6703\u5834\u53ca\u57d4\u91cc\u7684\u63a5\u99c1\u8eca<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column3434_ed688f-36 > .kt-inside-inner-col,.kadence-column3434_ed688f-36 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_ed688f-36 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_ed688f-36 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_ed688f-36 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_ed688f-36 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_ed688f-36{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_ed688f-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_ed688f-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_ed688f-36\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3434_9461a4-c7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3434_9461a4-c7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3434_9461a4-c7 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3434_9461a4-c7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_9461a4-c7 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3434_9461a4-c7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_9461a4-c7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3434_f399ca-5b > .kt-inside-inner-col,.kadence-column3434_f399ca-5b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_f399ca-5b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_f399ca-5b > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_f399ca-5b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_f399ca-5b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_f399ca-5b{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_f399ca-5b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_f399ca-5b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_f399ca-5b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_d11727-30, .wp-block-kadence-advancedheading.kt-adv-heading3434_d11727-30[data-kb-block=\"kb-adv-heading3434_d11727-30\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_d11727-30 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_d11727-30[data-kb-block=\"kb-adv-heading3434_d11727-30\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_d11727-30 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_d11727-30\">\u4ee5\u4e0b\u63a5\u99c1\u8eca\u670d\u52d9\u5c07\u65bc <strong>\u9031\u4e94<\/strong> \u5f9e <strong>\u53f0\u5317\u8eca\u7ad9\u6771\u4e09\u9580 <\/strong>\u51fa\u767c\u524d\u5f80\u57d4\u91cc\uff0c\u4e26\u65bc\u9031\u65e5\u8fd4\u56de\uff1a<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_c51748-3f:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_c51748-3f ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_c51748-3f ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_c51748-3f ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_c51748-3f ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_c51748-3f kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_3178a7-78 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_3178a7-78 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u661f\u671f\u4e94 10:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_329923-43 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_329923-43 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u661f\u671f\u4e94 10:30<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_9f2b8e-b2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_9f2b8e-b2 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u661f\u671f\u4e94 13:30<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_7c7a5a-fe .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_7c7a5a-fe kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u661f\u671f\u4e94 14:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_062439-8c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_062439-8c kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u661f\u671f\u4e94 17:00<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_130a50-96:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_130a50-96 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_130a50-96 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_130a50-96 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_130a50-96 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_130a50-96 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_b0332b-63 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_b0332b-63 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u9031\u65e513:00 \u5f9e\u57d4\u91cc\u51fa\u767c\u8fd4\u56de\u53f0\u5317<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_3ce714-96 > .kt-inside-inner-col,.kadence-column3434_3ce714-96 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_3ce714-96 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_3ce714-96 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_3ce714-96 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_3ce714-96 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_3ce714-96{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_3ce714-96 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_3ce714-96 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_3ce714-96\"><div class=\"kt-inside-inner-col\"><style>.kb-google-maps-container3434_af68db-8b{height:300px;}<\/style><div class=\"kb-google-maps-container kb-google-maps-container3434_af68db-8b  wp-block-kadence-googlemaps\" data-mapid=\"3434_af68db8b\"><iframe width=\"100%\" height=\"100%\"\n\t\t\t\t\t\t\tstyle=\"border:0\" loading=\"lazy\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBAM2o7PiQqwk15LC1XRH2e_KJ-jUa7KYk&#038;zoom=18&#038;maptype=satellite&#038;q=%E8%87%BA%E5%8C%97%E8%BB%8A%E6%9D%B1%E4%B8%89%E9%96%80\"\n\t\t\t\t\t\t\ttitle=\"Google map of \u81fa\u5317\u8eca\u6771\u4e09\u9580\"><\/iframe><\/div><script>function kb_google_map3434_af68db8b() { let center = { lat: 37.8201, lng: -122.4781}; let map = new google.maps.Map(document.getElementById(\"kb-google-map3434_af68db8b\"), {\n\t\t\t\t\t    zoom: 18,\n\t\t\t\t\t    center: center,mapTypeId: \"satellite\",});let marker = new google.maps.Marker({   position: { lat: 37.8201, lng: -122.4781},    map: map,  });}<\/script><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3434_a3501b-e8 > .kt-inside-inner-col,.kadence-column3434_a3501b-e8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_a3501b-e8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_a3501b-e8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_a3501b-e8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_a3501b-e8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_a3501b-e8{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_a3501b-e8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_a3501b-e8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_a3501b-e8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_30ce50-06:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_30ce50-06 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_30ce50-06 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_30ce50-06 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_30ce50-06 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_30ce50-06 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_c67da3-a6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_c67da3-a6\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u63a5\u99c1\u8eca\u5c07\u76f4\u63a5\u524d\u5f80\u6d3b\u52d5\u6703\u5834\uff08\u7de3\u6eaa\u884c\u68ee\u6797\u71df\u5730\uff09\u3002 <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_e3949f-fd .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_e3949f-fd\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u5982\u679c\u60a8\u9700\u8981\u7e7c\u7e8c\u524d\u5f80\u57d4\u91cc\u93ae\u4e2d\u5fc3\uff0c\u8acb\u5728 YCC \u71df\u5730\u524d\u63db\u4e58\u53e6\u4e00\u8f1b\u63a5\u99c1\u8eca\u3002 <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_d91f5f-ed .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_d91f5f-ed\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u63a5\u99c1\u8eca\u5c07\u7b49\u5f85\u7d04 45 \u5206\u9418\uff0c\u4ee5\u4fbf\u53c3\u52a0\u8005\u9818\u53d6\u6d3b\u52d5\u7269\u8cc7<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_27180d-28 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_27180d-28\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u8fd4\u56de\u53f0\u5317\uff1a<\/strong> \u9031\u65e5\u4e0b\u5348 1:00 \u5f9e\u6d3b\u52d5\u6703\u5834\uff08\u7de3\u6eaa\u884c\u68ee\u6797\u71df\u5730\uff09\u767c\u8eca\u3002\u63a5\u99c1\u8eca\u5c07\u5728\u71df\u5730\u6a4b\u524d\u7684\u4e3b\u8981\u9053\u8def\u4e0a\u7b49\u5019\uff0c\u6176\u795d\u6d3b\u52d5\u7d50\u675f\u5f8c\u7acb\u5373\u767c\u8eca\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_b6aab8-44 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_b6aab8-44\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u5ea7\u4f4d\u6709\u9650\uff0c\u8acb\u5728\u5831\u540d\u6642\u9810\u8a02\u5ea7\u4f4d\u3002\u60a8\u4e5f\u53ef\u4ee5\u70ba\u60a8\u7684\u540c\u884c\u89aa\u53cb\u9810\u8a02\u5ea7\u4f4d\uff08\u548c\u6d3b\u52d5\u9910\u9ede\uff09\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_3c66e9-86 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_3c66e9-86\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u8eca\u7a0b\u6642\u9593\u7d04 3 \u5c0f\u6642\uff08\u4ea4\u901a\u58c5\u585e\u6642\u53ef\u80fd\u8d85\u904e 4 \u5c0f\u6642\uff09\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_fc428e-3c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_fc428e-3c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u53f0\u5317\u8eca\u7ad9\u6771 3 \u9580\u4f4d\u7f6e\uff1a<\/strong> <a href=\"https:\/\/goo.gl\/maps\/6vnLnqTLHAG2\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/goo.gl\/maps\/6vnLnqTLHAG2<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_091c8e-fc .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_091c8e-fc\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u7de3\u6eaa\u884c\u68ee\u6797\u71df\u5730\uff08\u6d3b\u52d5\u6703\u5834\uff09\u4f4d\u7f6e\uff1a<\/strong> <a href=\"https:\/\/goo.gl\/maps\/rbEyGTbjGEFvw5HW7\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/goo.gl\/maps\/rbEyGTbjGEFvw5HW7<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_37fc7d-65 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_37fc7d-65\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u7dda\u4e0a\u9810\u8a02\uff1a<\/strong> \u5728\u5831\u540d\u671f\u9593\u63d0\u4f9b\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_98b425-35 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_98b425-35\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u4ea4\u901a\u63a5\u99c1\u7968<\/strong> \u6b32\u642d\u4e58\u63a5\u99c1\u8eca\uff0c\u8acb\u7531\u6b64\u9023\u7d50\u641c\u5c0b\u59d3\u540d\u53d6\u5f97\u865f\u78bc\u5e03\u53ca\u8eca\u7968\uff0c\u4e26\u5411\u5de5\u4f5c\u4eba\u54e1\u51fa\u793a\u53c3\u8cfd\u8005\u540d\u55ae\u4e2d\u7684\u7d00\u9304\uff1a <a href=\"https:\/\/formosatrail.com\/zh\/participants\/\">https:\/\/formosatrail.com\/participants\/<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-12 kt-pane3434_0d9156-bc\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><strong>\u9031\u516d\u65e9\u4e0a\u7531\u57d4\u91cc\u93ae\u4e2d\u5fc3\u642d\u4e58\u5df4\u58eb\u524d\u5f80\u6bd4\u8cfd\u8d77\u9ede<\/strong><\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column3434_45d043-23 > .kt-inside-inner-col,.kadence-column3434_45d043-23 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_45d043-23 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_45d043-23 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_45d043-23 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_45d043-23 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_45d043-23{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_45d043-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_45d043-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_45d043-23\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3434_f1dd95-81 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3434_f1dd95-81 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3434_f1dd95-81 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3434_f1dd95-81 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_f1dd95-81 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3434_f1dd95-81 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_f1dd95-81 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3434_fa0bc1-36 > .kt-inside-inner-col,.kadence-column3434_fa0bc1-36 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_fa0bc1-36 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_fa0bc1-36 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_fa0bc1-36 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_fa0bc1-36 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_fa0bc1-36{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_fa0bc1-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_fa0bc1-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_fa0bc1-36\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_0c545a-a4, .wp-block-kadence-advancedheading.kt-adv-heading3434_0c545a-a4[data-kb-block=\"kb-adv-heading3434_0c545a-a4\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_0c545a-a4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_0c545a-a4[data-kb-block=\"kb-adv-heading3434_0c545a-a4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_0c545a-a4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_0c545a-a4\">\u9031\u516d\u4e0a\u5348\u63d0\u4f9b\u5f9e\u57d4\u91cc\u5e02\u5340\u81f3\u8cfd\u4e8b\u8d77\u9ede\u7684\u63a5\u99c1\u5df4\u58eb\u670d\u52d9\uff0c\u8cbb\u7528\u70ba\u6bcf\u4eba\u65b0\u53f0\u5e63 100 \u5143\u3002\u5982\u679c\u60a8\u8a08\u5283\u4f4f\u5728\u57d4\u91cc\u5e02\u5340\uff0c\u6211\u5011\u5efa\u8b70\u60a8\u5728\u5831\u540d\u6642\u9810\u8a02\u6b64\u5df4\u58eb\u3002<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_b71240-f5, .wp-block-kadence-advancedheading.kt-adv-heading3434_b71240-f5[data-kb-block=\"kb-adv-heading3434_b71240-f5\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_b71240-f5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_b71240-f5[data-kb-block=\"kb-adv-heading3434_b71240-f5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_b71240-f5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_b71240-f5\"><br>\u5df4\u58eb\u6216\u5ec2\u578b\u8eca\u5c07\u5f9e\u57d4\u91cc\u8f49\u904b\u7ad9\u767c\u8eca\uff0c\u4e26\u505c\u9760\u53f0\u7063\u5730\u7406\u4e2d\u5fc3\u7891\uff0c\u767c\u8eca\u6642\u9593\u5982\u4e0b\uff1a<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_1227f9-bc:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_1227f9-bc ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_1227f9-bc ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_1227f9-bc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_1227f9-bc ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_1227f9-bc kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_7976dd-37 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_7976dd-37 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 3:00 (\u6700\u9069\u5408 75 \u516c\u91cc\u53ca 104 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_62c39c-81 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_62c39c-81 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 3:20 (\u6700\u9069\u5408 75 \u516c\u91cc\u53ca 104 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_b390ba-84 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_b390ba-84 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 4:00 (\u6700\u9069\u5408 40 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_d967bb-42 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_d967bb-42 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 4:20 (\u6700\u9069\u5408 40 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_3fb376-bb .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_3fb376-bb kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 4:40 (\u6700\u9069\u5408 40 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_57e892-fe .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_57e892-fe kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 5:40 (\u6700\u9069\u5408 10 \u516c\u91cc\u300118 \u516c\u91cc\u53ca 54 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_08b721-0a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_08b721-0a kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 6:00 (\u6700\u9069\u5408 10 \u516c\u91cc\u300118 \u516c\u91cc\u53ca 54 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_3188ee-4c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_3188ee-4c kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 6:20 (\u6700\u9069\u5408 10 \u516c\u91cc\u300118 \u516c\u91cc\u53ca 54 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_478e83-8c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_478e83-8c kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u51cc\u6668 6:40 (\u6700\u9069\u5408 10 \u516c\u91cc\u300118 \u516c\u91cc\u53ca 54 \u516c\u91cc\u7d44\u5225)<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_5a13b4-cc > .kt-inside-inner-col,.kadence-column3434_5a13b4-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_5a13b4-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_5a13b4-cc > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_5a13b4-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_5a13b4-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_5a13b4-cc{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_5a13b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_5a13b4-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_5a13b4-cc\"><div class=\"kt-inside-inner-col\"><style>.kb-google-maps-container3434_e9a243-04{height:300px;padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);}<\/style><div class=\"kb-google-maps-container kb-google-maps-container3434_e9a243-04  wp-block-kadence-googlemaps\" data-mapid=\"3434_e9a24304\"><iframe width=\"100%\" height=\"100%\"\n\t\t\t\t\t\t\tstyle=\"border:0\" loading=\"lazy\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBAM2o7PiQqwk15LC1XRH2e_KJ-jUa7KYk&#038;zoom=19&#038;maptype=satellite&#038;q=%E5%9F%94%E9%87%8C%E8%BD%89%E9%81%8B%E7%AB%99\"\n\t\t\t\t\t\t\ttitle=\"Google map of \u57d4\u91cc\u8f49\u904b\u7ad9\"><\/iframe><\/div><script>function kb_google_map3434_e9a24304() { let center = { lat: 37.8201, lng: -122.4781}; let map = new google.maps.Map(document.getElementById(\"kb-google-map3434_e9a24304\"), {\n\t\t\t\t\t    zoom: 19,\n\t\t\t\t\t    center: center,mapTypeId: \"satellite\",});let marker = new google.maps.Marker({   position: { lat: 37.8201, lng: -122.4781},    map: map,  });}<\/script>\n\n<style>.kb-google-maps-container3434_50c47a-5a{height:300px;padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);}<\/style><div class=\"kb-google-maps-container kb-google-maps-container3434_50c47a-5a  wp-block-kadence-googlemaps\" data-mapid=\"3434_50c47a5a\"><iframe width=\"100%\" height=\"100%\"\n\t\t\t\t\t\t\tstyle=\"border:0\" loading=\"lazy\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBAM2o7PiQqwk15LC1XRH2e_KJ-jUa7KYk&#038;zoom=19&#038;maptype=satellite&#038;q=%E8%87%BA%E7%81%A3%E5%9C%B0%E7%90%86%E4%B8%AD%E5%BF%83%E7%A2%91\"\n\t\t\t\t\t\t\ttitle=\"Google map of \u81fa\u7063\u5730\u7406\u4e2d\u5fc3\u7891\"><\/iframe><\/div><script>function kb_google_map3434_50c47a5a() { let center = { lat: 37.8201, lng: -122.4781}; let map = new google.maps.Map(document.getElementById(\"kb-google-map3434_50c47a5a\"), {\n\t\t\t\t\t    zoom: 19,\n\t\t\t\t\t    center: center,mapTypeId: \"satellite\",});let marker = new google.maps.Marker({   position: { lat: 37.8201, lng: -122.4781},    map: map,  });}<\/script><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3434_9896b8-d9 > .kt-inside-inner-col,.kadence-column3434_9896b8-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_9896b8-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_9896b8-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_9896b8-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_9896b8-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_9896b8-d9{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_9896b8-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_9896b8-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_9896b8-d9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_f20acf-45, .wp-block-kadence-advancedheading.kt-adv-heading3434_f20acf-45[data-kb-block=\"kb-adv-heading3434_f20acf-45\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_f20acf-45 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_f20acf-45[data-kb-block=\"kb-adv-heading3434_f20acf-45\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_f20acf-45 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_f20acf-45\">\u63d0\u9192:<br>\u5df4\u58eb\u8def\u7dda\u5716\uff1a <a href=\"https:\/\/goo.gl\/maps\/UAgoWi7X8LRBPQLf8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/goo.gl\/maps\/UAgoWi7X8LRBPQLf8<\/a><br>\u65e9\u4e0a\u5c07\u63d0\u4f9b\u5f9e\u57d4\u91cc\u524d\u5f80\u8cfd\u4e8b\u8d77\u8dd1\u6703\u5834\u7684\u63a5\u99c1\u5df4\u58eb\u670d\u52d9\u3002\u7531\u65bc\u8a08\u7a0b\u8eca\u6578\u91cf\u6709\u9650\uff0c\u5c24\u5176\u662f\u5728\u6e05\u6668\uff0c\u63a5\u99c1\u5df4\u58eb\u662f\u524d\u5f80\u8d77\u8dd1\u7dda\u7684\u63a8\u85a6\u4e14\u6700\u53ef\u9760\u7684\u65b9\u5f0f\u3002<br>\u8cfd\u5f8c\u5f9e\u6703\u5834\u8fd4\u56de\u57d4\u91cc\uff0c\u60a8\u53ef\u9078\u64c7\u642d\u4e58\u8a08\u7a0b\u8eca\uff0c\u9810\u8a08\u8cbb\u7528\u7d04\u70ba\u6bcf\u8eca\u65b0\u53f0\u5e63 200 \u5143\u3002\u8acb\u6ce8\u610f\uff0c\u8a08\u7a0b\u8eca\u7684\u4f9b\u61c9\u60c5\u6cc1\u53ef\u80fd\u6703\u6709\u6240\u4e0d\u540c\u3002\u60a8\u53ef\u4ee5\u5728\u63a5\u5f85\u8655\u9810\u7d04\u8a08\u7a0b\u8eca\uff0c\u6216\u81f4\u96fb\u4ee5\u4e0b\u6240\u5217\u7684\u96fb\u8a71\u865f\u78bc\u3002<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3434_f02da7-84 > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id3434_f02da7-84 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id3434_f02da7-84 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3434_f02da7-84 > .kt-row-layout-overlay{opacity:0.85;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id3434_f02da7-84 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_f02da7-84 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_f02da7-84 alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-bottom kb-theme-content-width\">\n<style>.kadence-column3434_0d0547-ea > .kt-inside-inner-col{display:flex;}.kadence-column3434_0d0547-ea > .kt-inside-inner-col,.kadence-column3434_0d0547-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_0d0547-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_0d0547-ea > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_0d0547-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_0d0547-ea{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_0d0547-ea{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_0d0547-ea > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_0d0547-ea > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_0d0547-ea{text-align:left;}.kadence-column3434_0d0547-ea{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_0d0547-ea{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_0d0547-ea{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_0d0547-ea > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column3434_0d0547-ea > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_0d0547-ea{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_0d0547-ea{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_0d0547-ea > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_0d0547-ea > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_0d0547-ea kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_85ee1b-f3, .wp-block-kadence-advancedheading.kt-adv-heading3434_85ee1b-f3[data-kb-block=\"kb-adv-heading3434_85ee1b-f3\"]{font-size:32px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_85ee1b-f3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_85ee1b-f3[data-kb-block=\"kb-adv-heading3434_85ee1b-f3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3434_85ee1b-f3 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading3434_85ee1b-f3\">\u6a5f\u5834<\/h2>\n\n\n<style>.kt-accordion-id3434_8b6aef-c0 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);}.kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette9, #ffffff);font-size:18px;line-height:1.2;font-weight:600;text-transform:none;color:var(--global-palette3, #1A202C);padding-top:15px;padding-right:10px;padding-bottom:15px;padding-left:10px;}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner, .kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner h1, .kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner h2, .kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner h3, .kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner h4, .kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner h5, .kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_8b6aef-c0 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette3, #1A202C);background:var(--global-palette9, #ffffff);border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_8b6aef-c0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette3, #1A202C);background:var(--global-palette9, #ffffff);border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_8b6aef-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_8b6aef-c0 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id3434_8b6aef-c0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kt-accordion-id3434_8b6aef-c0 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3434_8b6aef-c0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_8b6aef-c0 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_8b6aef-c0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_8b6aef-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3434_8b6aef-c0 kt-accordion-has-8-panes kt-active-pane-3 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane3434_431346-57\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u5f9e\u6843\u5712\u6a5f\u5834\u51fa\u767c\uff08\u53f0\u5317\uff09<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column3434_66b66e-eb > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column3434_66b66e-eb > .kt-inside-inner-col,.kadence-column3434_66b66e-eb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_66b66e-eb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_66b66e-eb > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_66b66e-eb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_66b66e-eb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_66b66e-eb{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_66b66e-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_66b66e-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_66b66e-eb\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_4553a0-76, .wp-block-kadence-advancedheading.kt-adv-heading3434_4553a0-76[data-kb-block=\"kb-adv-heading3434_4553a0-76\"]{padding-top:0px;margin-bottom:30px;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_4553a0-76 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_4553a0-76[data-kb-block=\"kb-adv-heading3434_4553a0-76\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_4553a0-76 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_4553a0-76\">\u4e0d\u63d0\u4f9b \u2014 \u4f46\u6211\u5011\u53ef\u4ee5\u5354\u52a9\u60a8 \u2014 \u8acb\u8207\u6211\u5011\u806f\u7e6b<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_4ae972-12, .wp-block-kadence-advancedheading.kt-adv-heading3434_4ae972-12[data-kb-block=\"kb-adv-heading3434_4ae972-12\"]{margin-bottom:30px;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_4ae972-12 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_4ae972-12[data-kb-block=\"kb-adv-heading3434_4ae972-12\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_4ae972-12 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_4ae972-12\">\u5f9e\u6843\u5712\u6a5f\u5834\u524d\u5f80\u57d4\u91cc\u7684\u6700\u4f73\u65b9\u5f0f\u662f <strong>\u642d\u4e58\u6377\u904b<\/strong> \u81f3\u53f0\u5317\u8eca\u7ad9\u3002\u7136\u5f8c\uff0c\u5f9e\u53f0\u5317\u8eca\u7ad9\u8f49\u4e58\u4e3b\u8fa6\u55ae\u4f4d\u524d\u5f80\u57d4\u91cc\u548c\u6703\u5834\u7684\u63a5\u99c1\u5df4\u58eb\uff08\u5982\u4e0a\u8ff0\u8cc7\u8a0a\uff09\u3002<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_3651aa-75 > .kt-inside-inner-col{padding-right:0px;}.kadence-column3434_3651aa-75 > .kt-inside-inner-col,.kadence-column3434_3651aa-75 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_3651aa-75 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_3651aa-75 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_3651aa-75 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_3651aa-75 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_3651aa-75{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_3651aa-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_3651aa-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_3651aa-75\"><div class=\"kt-inside-inner-col\"><style>.kb-google-maps-container3434_61f30b-c4{height:300px;}.kb-google-maps-container3434_61f30b-c4{filter:sepia(30%);}<\/style><div class=\"kb-google-maps-container kb-google-maps-container3434_61f30b-c4  wp-block-kadence-googlemaps\" data-mapid=\"3434_61f30bc4\"><iframe width=\"100%\" height=\"100%\"\n\t\t\t\t\t\t\tstyle=\"border:0\" loading=\"lazy\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBAM2o7PiQqwk15LC1XRH2e_KJ-jUa7KYk&#038;zoom=11&#038;maptype=roadmap&#038;q=Taoyuan+airport\"\n\t\t\t\t\t\t\ttitle=\"Google map of Taoyuan airport\"><\/iframe><\/div><script>function kb_google_map3434_61f30bc4() { let center = { lat: 37.8201, lng: -122.4781}; let map = new google.maps.Map(document.getElementById(\"kb-google-map3434_61f30bc4\"), {\n\t\t\t\t\t    zoom: 11,\n\t\t\t\t\t    center: center,});let marker = new google.maps.Marker({   position: { lat: 37.8201, lng: -122.4781},    map: map,  });}<\/script><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_47beb0-34 > .kt-inside-inner-col{display:flex;}.kadence-column3434_47beb0-34 > .kt-inside-inner-col,.kadence-column3434_47beb0-34 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_47beb0-34 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_47beb0-34 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_47beb0-34 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_47beb0-34{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_47beb0-34{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_47beb0-34 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_47beb0-34 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_47beb0-34{text-align:left;}.kadence-column3434_47beb0-34{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_47beb0-34{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_47beb0-34{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_47beb0-34 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column3434_47beb0-34 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_47beb0-34{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_47beb0-34{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_47beb0-34 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_47beb0-34 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_47beb0-34 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id3434_e82532-a4 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);}.kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette9, #ffffff);font-size:18px;line-height:1.2;font-weight:600;text-transform:none;color:var(--global-palette3, #1A202C);padding-top:15px;padding-right:10px;padding-bottom:15px;padding-left:10px;}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner, .kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner h1, .kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner h2, .kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner h3, .kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner h4, .kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner h5, .kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_e82532-a4 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette3, #1A202C);background:var(--global-palette9, #ffffff);border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_e82532-a4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette3, #1A202C);background:var(--global-palette9, #ffffff);border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_e82532-a4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_e82532-a4 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 1024px){.kt-accordion-id3434_e82532-a4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kt-accordion-id3434_e82532-a4 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3434_e82532-a4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_e82532-a4 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_e82532-a4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_e82532-a4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3434_e82532-a4 kt-accordion-has-8-panes kt-active-pane-3 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane3434_885c54-74\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u5f9e\u53f0\u4e2d\u6a5f\u5834\u51fa\u767c (RMQ)<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column3434_26b33f-16 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column3434_26b33f-16 > .kt-inside-inner-col,.kadence-column3434_26b33f-16 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_26b33f-16 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_26b33f-16 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_26b33f-16 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_26b33f-16 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_26b33f-16{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_26b33f-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_26b33f-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_26b33f-16\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_50871a-c4, .wp-block-kadence-advancedheading.kt-adv-heading3434_50871a-c4[data-kb-block=\"kb-adv-heading3434_50871a-c4\"]{padding-top:0px;margin-bottom:30px;font-weight:normal;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_50871a-c4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_50871a-c4[data-kb-block=\"kb-adv-heading3434_50871a-c4\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_50871a-c4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_50871a-c4\">\u4e0d\u63d0\u4f9b \u2014 \u4f46\u6211\u5011\u53ef\u4ee5\u5354\u52a9\u60a8 \u2014 \u8acb\u8207\u6211\u5011\u806f\u7e6b<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_17368a-98 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kadence-column3434_17368a-98 > .kt-inside-inner-col,.kadence-column3434_17368a-98 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_17368a-98 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_17368a-98 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_17368a-98 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_17368a-98 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_17368a-98{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_17368a-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_17368a-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_17368a-98\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id3434_914ac4-b4 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id3434_914ac4-b4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_914ac4-b4 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id3434_914ac4-b4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_914ac4-b4:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id3434_914ac4-b4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_914ac4-b4 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id3434_914ac4-b4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id3434_914ac4-b4 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3434_914ac4-b4 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id3434_914ac4-b4 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_914ac4-b4 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id3434_914ac4-b4 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_914ac4-b4 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3434_914ac4-b4 kt-accordion-has-2-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane3434_47abee-ca\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u5f9e\u53f0\u4e2d\u6a5f\u5834\u5230\u57d4\u91cc\u7684\u516c\u8eca\uff1a<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_b3772b-41, .wp-block-kadence-advancedheading.kt-adv-heading3434_b3772b-41[data-kb-block=\"kb-adv-heading3434_b3772b-41\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_b3772b-41 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_b3772b-41[data-kb-block=\"kb-adv-heading3434_b3772b-41\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_b3772b-41 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_b3772b-41\"><br>\u5728\u53f0\u4e2d\u570b\u969b\u6a5f\u5834\uff08RMQ\uff09\uff0c\u8acb\u524d\u5f80\u6a5f\u5834\u5df4\u58eb\u7ad9\u642d\u4e58 <strong>156 \u865f\u516c\u8eca<\/strong> \uff0c\u9019\u689d\u8def\u7dda\u6703\u76f4\u63a5\u5c07\u4f60\u9001\u5230 \u53f0\u4e2d\u9ad8\u9435\u7ad9\u3002<br>\u62b5\u9054\u9ad8\u9435\u7ad9\u5f8c\uff0c\u8acb\u524d\u5f80 \u4e00\u6a13\u7684 <strong>5 \u865f\u51fa\u53e3<\/strong> \uff0c\u8a72\u8655\u662f\u5df4\u58eb\u8f49\u904b\u7ad9\u3002\u627e\u5230 <strong>\u5357\u6295\u5ba2\u904b<\/strong> \u7684\u670d\u52d9\u6ac3\u6aaf\u6216\u516c\u8eca\u7ad9\u724c\u3002<br>\u63a5\u8457\u642d\u4e58 <strong>\u5357\u6295\u5ba2\u904b\u7684 6670 \u865f\u8def\u7dda\uff08\u6216\u5176\u4ed6\u958b\u5f80\u57d4\u91cc\u7684\u76f4\u9054\u8def\u7dda\uff09<\/strong> \uff0c\u524d\u5f80 <strong>\u57d4\u91cc\u8f49\u904b\u7ad9<\/strong>\u3002\u9019\u4e9b\u516c\u8eca\u73ed\u6b21\u983b\u7e41\uff0c\u8eca\u7a0b\u7d04\u70ba 40 \u81f3 50 \u5206\u9418\u3002<br><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane3434_472d96-c9\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u5f9e\u53f0\u4e2d\u6a5f\u5834\u5230\u57d4\u91cc\u7684\u8a08\u7a0b\u8eca<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_c08f5e-6d, .wp-block-kadence-advancedheading.kt-adv-heading3434_c08f5e-6d[data-kb-block=\"kb-adv-heading3434_c08f5e-6d\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_c08f5e-6d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_c08f5e-6d[data-kb-block=\"kb-adv-heading3434_c08f5e-6d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_c08f5e-6d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_c08f5e-6d\">\u4fbf\u6377\u7684\u8a08\u7a0b\u8eca\u670d\u52d9\uff1a\u6700\u5feb\u901f\u4e14\u7121\u9700\u8f49\u4e58\uff0c\u5f9e\u6a5f\u5834\u76f4\u9054\u57d4\u91cc\u4f4f\u5bbf\uff0c\u514d\u53bb\u642d\u4e58\u516c\u8eca\u4e26\u67e5\u627e\u8def\u7dda\u8207\u6642\u9593\u8868\u7684\u9ebb\u7169\u3002<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_1f34af-b9, .wp-block-kadence-advancedheading.kt-adv-heading3434_1f34af-b9[data-kb-block=\"kb-adv-heading3434_1f34af-b9\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_1f34af-b9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_1f34af-b9[data-kb-block=\"kb-adv-heading3434_1f34af-b9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_1f34af-b9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_1f34af-b9\">\u8a08\u7a0b\u8eca\u8cbb\u7528\u4ee5\u8a08\u7a0b\u8868\u8a08\u7b97\uff0c\u5305\u542b\u8d77\u6b65\u8cbb\u3001\u6bcf\u516c\u91cc\u6536\u8cbb\uff0c\u4e26\u53ef\u80fd\u6709\u984d\u5916\u7684\u9644\u52a0\u8cbb\uff08\u5982\u591c\u9593\u884c\u99db\uff09\u3002<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_042b80-b5, .wp-block-kadence-advancedheading.kt-adv-heading3434_042b80-b5[data-kb-block=\"kb-adv-heading3434_042b80-b5\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_042b80-b5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_042b80-b5[data-kb-block=\"kb-adv-heading3434_042b80-b5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_042b80-b5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_042b80-b5\"><br>\u8a08\u7a0b\u8eca\u53ef\u5728\u6a5f\u5834\u822a\u7ad9\u6a13\u5916\u7684\u6307\u5b9a\u8a08\u7a0b\u8eca\u7ad9\u8f15\u9b06\u642d\u4e58\uff08\u901a\u5e38\u4f4d\u65bc\u570b\u969b\u822a\u7ad9\u6a13\u7684B1\u6a13\u5c64\uff09\u3002&nbsp;<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_8688d6-60, .wp-block-kadence-advancedheading.kt-adv-heading3434_8688d6-60[data-kb-block=\"kb-adv-heading3434_8688d6-60\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_8688d6-60 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_8688d6-60[data-kb-block=\"kb-adv-heading3434_8688d6-60\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_8688d6-60 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_8688d6-60\"><br><strong>\u9810\u4f30\u50f9\u683c\uff1a<\/strong> \u5f9e\u53f0\u4e2d\u6a5f\u5834\u642d\u4e58\u8a08\u7a0b\u8eca\u76f4\u9054\u57d4\u91cc\uff0c\u8cbb\u7528\u5927\u7d04\u5728 <strong>NT$1500\u81f3NT$2000\u6216\u66f4\u591a<\/strong> \u3002\u5177\u9ad4\u8cbb\u7528\u6703\u6839\u64da\u4ea4\u901a\u60c5\u6cc1\u3001\u57d4\u91cc\u7684\u5177\u9ad4\u4f4d\u7f6e\u4ee5\u53ca\u9644\u52a0\u8cbb\u800c\u6709\u6240\u8b8a\u52d5\u3002\u8eca\u7a0b\u5927\u7d04\u9700\u898150\u81f360\u5206\u9418\u3002<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_51494f-ae > .kt-inside-inner-col{padding-right:0px;}.kadence-column3434_51494f-ae > .kt-inside-inner-col,.kadence-column3434_51494f-ae > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_51494f-ae > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_51494f-ae > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_51494f-ae > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_51494f-ae > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_51494f-ae{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_51494f-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_51494f-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_51494f-ae\"><div class=\"kt-inside-inner-col\"><style>.kb-google-maps-container3434_a58964-fc{height:300px;}.kb-google-maps-container3434_a58964-fc{filter:sepia(30%);}<\/style><div class=\"kb-google-maps-container kb-google-maps-container3434_a58964-fc  wp-block-kadence-googlemaps\" data-mapid=\"3434_a58964fc\"><iframe width=\"100%\" height=\"100%\"\n\t\t\t\t\t\t\tstyle=\"border:0\" loading=\"lazy\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBAM2o7PiQqwk15LC1XRH2e_KJ-jUa7KYk&#038;zoom=11&#038;maptype=roadmap&#038;q=Taichung+airport\"\n\t\t\t\t\t\t\ttitle=\"Google map of Taichung airport\"><\/iframe><\/div><script>function kb_google_map3434_a58964fc() { let center = { lat: 37.8201, lng: -122.4781}; let map = new google.maps.Map(document.getElementById(\"kb-google-map3434_a58964fc\"), {\n\t\t\t\t\t    zoom: 11,\n\t\t\t\t\t    center: center,});let marker = new google.maps.Marker({   position: { lat: 37.8201, lng: -122.4781},    map: map,  });}<\/script><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3434_0317fe-1b > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id3434_0317fe-1b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id3434_0317fe-1b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3434_0317fe-1b > .kt-row-layout-overlay{opacity:0.00;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id3434_0317fe-1b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_0317fe-1b > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_0317fe-1b alignfull has-theme-palette4-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom kb-theme-content-width\">\n<style>.kadence-column3434_ec8149-cc > .kt-inside-inner-col{display:flex;}.kadence-column3434_ec8149-cc > .kt-inside-inner-col,.kadence-column3434_ec8149-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_ec8149-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_ec8149-cc > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_ec8149-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_ec8149-cc{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_ec8149-cc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_ec8149-cc > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_ec8149-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_ec8149-cc{text-align:left;}.kadence-column3434_ec8149-cc{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_ec8149-cc{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_ec8149-cc{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_ec8149-cc > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column3434_ec8149-cc > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_ec8149-cc{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_ec8149-cc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_ec8149-cc > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_ec8149-cc > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_ec8149-cc kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_e879b2-65, .wp-block-kadence-advancedheading.kt-adv-heading3434_e879b2-65[data-kb-block=\"kb-adv-heading3434_e879b2-65\"]{font-size:32px;font-style:normal;color:#ffb121;}.wp-block-kadence-advancedheading.kt-adv-heading3434_e879b2-65 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_e879b2-65[data-kb-block=\"kb-adv-heading3434_e879b2-65\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3434_e879b2-65 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_e879b2-65\">\u8a08\u7a0b\u8eca <\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_5a6140-2a > .kt-inside-inner-col{display:flex;}.kadence-column3434_5a6140-2a > .kt-inside-inner-col,.kadence-column3434_5a6140-2a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_5a6140-2a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_5a6140-2a > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_5a6140-2a > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_5a6140-2a{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_5a6140-2a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_5a6140-2a > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_5a6140-2a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_5a6140-2a{text-align:left;}.kadence-column3434_5a6140-2a{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_5a6140-2a{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_5a6140-2a{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_5a6140-2a > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column3434_5a6140-2a > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_5a6140-2a{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_5a6140-2a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_5a6140-2a > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_5a6140-2a > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_5a6140-2a kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id3434_2f9a57-a5 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);}.kt-accordion-id3434_2f9a57-a5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:rgba(255,255,255,0);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette7, #EDF2F7);font-size:18px;line-height:1.2;font-weight:600;text-transform:none;color:var(--global-palette3, #1A202C);padding-top:15px;padding-right:20px;padding-bottom:15px;padding-left:0px;}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_2f9a57-a5 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette9, #ffffff);background:var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette5, #4A5568);}.kt-accordion-id3434_2f9a57-a5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette4, #2D3748);background:#ffb121;border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_2f9a57-a5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffb121;}@media all and (max-width: 1024px){.kt-accordion-id3434_2f9a57-a5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;}}@media all and (max-width: 1024px){.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_2f9a57-a5 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 1024px){.kt-accordion-id3434_2f9a57-a5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-accordion-id3434_2f9a57-a5 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3434_2f9a57-a5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;}.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_2f9a57-a5 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_2f9a57-a5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_2f9a57-a5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3434_2f9a57-a5 kt-accordion-has-12-panes kt-active-pane-8 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"true\" data-start-open=\"8\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-9 kt-pane3434_c986ed-3b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u57d4\u91cc\u7684\u8a08\u7a0b\u8eca<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column3434_8a5fbb-e7 > .kt-inside-inner-col,.kadence-column3434_8a5fbb-e7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_8a5fbb-e7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_8a5fbb-e7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_8a5fbb-e7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_8a5fbb-e7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_8a5fbb-e7{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_8a5fbb-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_8a5fbb-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_8a5fbb-e7\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3434_8d1a9a-20 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3434_8d1a9a-20 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3434_8d1a9a-20 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id3434_8d1a9a-20 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_8d1a9a-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_8d1a9a-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_8d1a9a-20 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3434_f8b457-ff > .kt-inside-inner-col,.kadence-column3434_f8b457-ff > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_f8b457-ff > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_f8b457-ff > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_f8b457-ff > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_f8b457-ff > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_f8b457-ff{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_f8b457-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_f8b457-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_f8b457-ff\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_aac1f9-89, .wp-block-kadence-advancedheading.kt-adv-heading3434_aac1f9-89[data-kb-block=\"kb-adv-heading3434_aac1f9-89\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_aac1f9-89 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_aac1f9-89[data-kb-block=\"kb-adv-heading3434_aac1f9-89\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_aac1f9-89 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_aac1f9-89\">\u4ee5\u4e0b\u63a5\u99c1\u8eca\u670d\u52d9\u5c07\u65bc <strong>\u9031\u4e94<\/strong> \u5f9e <strong>\u53f0\u5317\u8eca\u7ad9\u6771\u4e09\u9580 <\/strong>\u51fa\u767c\u524d\u5f80\u57d4\u91cc\uff0c\u4e26\u65bc\u9031\u65e5\u8fd4\u56de\uff1a<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_ab21be-4c:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_ab21be-4c ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_ab21be-4c ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_ab21be-4c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_ab21be-4c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items3434_ab21be-4c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette9, #ffffff);color:var(--global-palette9, #ffffff);}.kt-svg-icon-list-items3434_ab21be-4c ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_ab21be-4c kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_a75013-52 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_a75013-52 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_taxi kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u8a08\u7a0b\u8eca\u7684\u8eca\u8cc7\u70ba\u6bcf\u516c\u91ccNT$25\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_8d1473-aa .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_8d1473-aa kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_taxi kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u5f9e\u57d4\u91cc\u5e02\u4e2d\u5fc3\u5230\u6bd4\u8cfd\u5834\u5730\u7684\u9810\u4f30\u8eca\u8cc7\u7d04\u70baNT$200\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_83cb2b-b4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_83cb2b-b4 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_taxi kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u6211\u5011\u5efa\u8b70\u901a\u904e\u98ef\u5e97\u6ac3\u6aaf\u8a02\u8eca\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_f4b1fa-be .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_f4b1fa-be kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_taxi kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u8acb\u6ce8\u610f\uff0c\u6bd4\u8cfd\u958b\u59cb\u524d\u65e9\u4e0a\u8a08\u7a0b\u8eca\u7684\u4f9b\u61c9\u6703\u975e\u5e38\u6709\u9650 \u2013 \u5f37\u70c8\u5efa\u8b70\u4f7f\u7528\u63a5\u99c1\u8eca\u670d\u52d9\u3002<\/strong><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_13e028-68 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_13e028-68 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_taxi kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u70ba\u4e86\u65b9\u4fbf\u5411\u8a08\u7a0b\u8eca\u53f8\u6a5f\u51fa\u793a\uff0c <strong>\u8acb\u5c07\u60a8\u98ef\u5e97\u7684\u5730\u5740\u4fdd\u5b58\u70ba\u4e2d\u6587<\/strong> \u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_b3e6ac-94 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_b3e6ac-94 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_taxi kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u7d66\u8a08\u7a0b\u8eca\u53f8\u6a5f\u7684\u6703\u5834\u5730\u5740\uff1a <strong>\u7de3\u6eaa\u884c\u68ee\u6797\u71df\u5730 &#8211; 545\u5357\u6295\u7e23\u57d4\u91cc\u93ae\u4e7e\u6eaa\u666f\u89c0\u6a4b545\u865f <\/strong><br>(YYC campsite &#8211; No. 545, Qianxi Landscape Bridge, Puli Township, Nantou County, 545)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_0509d2-43 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_0509d2-43 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_taxi kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u4e0b\u8eca\u53ca\u63a5\u9001\u9ede\uff1a\u8a08\u7a0b\u8eca\u6216\u63a5\u99c1\u8eca\u7684\u6307\u5b9a\u4e0b\u8eca\u53ca\u63a5\u9001\u9ede\u70ba\u901a\u5f80YYC\u71df\u5730\u6a4b\u4e4b\u524d\u7684\u5730\u65b9\uff1a <a href=\"https:\/\/maps.app.goo.gl\/iSjsUmpbxzw7gWG3A\">Google Maps Link<\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_2ba847-02:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_2ba847-02 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_2ba847-02 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_2ba847-02 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_2ba847-02 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_2ba847-02 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_aefd7a-7a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_aefd7a-7a kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_bus-alt kt-svg-icon-list-single\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M488 128h-8V80c0-44.8-99.2-80-224-80S32 35.2 32 80v48h-8c-13.25 0-24 10.74-24 24v80c0 13.25 10.75 24 24 24h8v160c0 17.67 14.33 32 32 32v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h192v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h6.4c16 0 25.6-12.8 25.6-25.6V256h8c13.25 0 24-10.75 24-24v-80c0-13.26-10.75-24-24-24zM160 72c0-4.42 3.58-8 8-8h176c4.42 0 8 3.58 8 8v16c0 4.42-3.58 8-8 8H168c-4.42 0-8-3.58-8-8V72zm-48 328c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm128-112H128c-17.67 0-32-14.33-32-32v-96c0-17.67 14.33-32 32-32h112v160zm32 0V128h112c17.67 0 32 14.33 32 32v96c0 17.67-14.33 32-32 32H272zm128 112c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u9031\u65e513:00 \u5f9e\u57d4\u91cc\u51fa\u767c\u8fd4\u56de\u53f0\u5317<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_5f4255-27 > .kt-inside-inner-col,.kadence-column3434_5f4255-27 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_5f4255-27 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_5f4255-27 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_5f4255-27 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_5f4255-27 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_5f4255-27{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_5f4255-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_5f4255-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_5f4255-27\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3434_e2d3a5-a4 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3434_e2d3a5-a4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3434_e2d3a5-a4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3434_e2d3a5-a4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_e2d3a5-a4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_e2d3a5-a4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_e2d3a5-a4 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3434_6c57a1-ee > .kt-inside-inner-col,.kadence-column3434_6c57a1-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_6c57a1-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_6c57a1-ee > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_6c57a1-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_6c57a1-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_6c57a1-ee{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_6c57a1-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_6c57a1-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_6c57a1-ee\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons3434_983966-2a .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons3434_983966-2a{justify-content:center;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons3434_983966-2a alignnone\"><style>.kt-svg-item-3434_c61cbf-3d .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-3434_c61cbf-3d .kb-svg-icon-wrap{color:#ffb121;font-size:150px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-3434_c61cbf-3d\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_taxi\"><svg viewbox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M462 241.64l-22-84.84c-9.6-35.2-41.6-60.8-76.8-60.8H352V64c0-17.67-14.33-32-32-32H192c-17.67 0-32 14.33-32 32v32h-11.2c-35.2 0-67.2 25.6-76.8 60.8l-22 84.84C21.41 248.04 0 273.47 0 304v48c0 23.63 12.95 44.04 32 55.12V448c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-40.88c19.05-11.09 32-31.5 32-55.12v-48c0-30.53-21.41-55.96-50-62.36zM96 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32zm20.55-112l17.2-66.36c2.23-8.16 9.59-13.64 15.06-13.64h214.4c5.47 0 12.83 5.48 14.85 12.86L395.45 240h-278.9zM416 352c-17.67 0-32-14.33-32-32s14.33-32 32-32 32 14.33 32 32-14.33 32-32 32z\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_19b4a3-15 > .kt-inside-inner-col{display:flex;}.kadence-column3434_19b4a3-15 > .kt-inside-inner-col,.kadence-column3434_19b4a3-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_19b4a3-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_19b4a3-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column3434_19b4a3-15 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column3434_19b4a3-15 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column3434_19b4a3-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_19b4a3-15{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_19b4a3-15{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_19b4a3-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3434_19b4a3-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_19b4a3-15{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_19b4a3-15{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_19b4a3-15{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_19b4a3-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3434_19b4a3-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_19b4a3-15{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_19b4a3-15{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_19b4a3-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3434_19b4a3-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_19b4a3-15\"><div class=\"kt-inside-inner-col\"><style>.kb-image3434_151ec0-e9.kb-image-is-ratio-size, .kb-image3434_151ec0-e9 .kb-image-is-ratio-size{max-width:200px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3434_151ec0-e9.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3434_151ec0-e9 .kb-image-is-ratio-size{align-self:unset;}.kb-image3434_151ec0-e9 figure{max-width:200px;}.kb-image3434_151ec0-e9 .image-is-svg, .kb-image3434_151ec0-e9 .image-is-svg img{width:100%;}.kb-image3434_151ec0-e9 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3434_151ec0-e9\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/04\/Bus-Taxi-YCC.webp\" alt=\"\" class=\"kb-img wp-image-4457\" srcset=\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/04\/Bus-Taxi-YCC.webp 500w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/04\/Bus-Taxi-YCC-300x300.webp 300w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/04\/Bus-Taxi-YCC-150x150.webp 150w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/04\/Bus-Taxi-YCC-12x12.webp 12w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3434_903dd5-dd > .kt-inside-inner-col,.kadence-column3434_903dd5-dd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_903dd5-dd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_903dd5-dd > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_903dd5-dd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_903dd5-dd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_903dd5-dd{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_903dd5-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_903dd5-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_903dd5-dd\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id3434_a41a84-0a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3434_a41a84-0a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_a41a84-0a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3434_a1e22d-76 > .kt-inside-inner-col,.kadence-column3434_a1e22d-76 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_a1e22d-76 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_a1e22d-76 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_a1e22d-76 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_a1e22d-76 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_a1e22d-76{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_a1e22d-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_a1e22d-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_a1e22d-76\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_ed8f01-14, .wp-block-kadence-advancedheading.kt-adv-heading3434_ed8f01-14[data-kb-block=\"kb-adv-heading3434_ed8f01-14\"]{text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_ed8f01-14 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_ed8f01-14[data-kb-block=\"kb-adv-heading3434_ed8f01-14\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_ed8f01-14 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_ed8f01-14\"><strong>24\u5c0f\u6642\u7576\u5730\u8a08\u7a0b\u8eca<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_5c1f29-8c, .wp-block-kadence-advancedheading.kt-adv-heading3434_5c1f29-8c[data-kb-block=\"kb-adv-heading3434_5c1f29-8c\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_5c1f29-8c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_5c1f29-8c[data-kb-block=\"kb-adv-heading3434_5c1f29-8c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_5c1f29-8c wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_5c1f29-8c\">\u7576\u5730\u79c1\u4eba\u8a08\u7a0b\u8eca\uff0c\u5168\u5929\u5019\u670d\u52d9<br>\u9069\u5408\u9031\u516d\u4e0b\u5348\u548c\u665a\u4e0a\u7684\u6bd4\u8cfd\u5834\u5730\u56de\u7a0b\u3002<br>\u96fb\u8a71: <strong>0968-038963<\/strong> <br>\u57d4\u91cc\u6d2a\u82b1\u8a08\u7a0b\u8eca \u2013 \u5176\u555f\u5bcc \u5148\u751f<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_167a8f-9d > .kt-inside-inner-col,.kadence-column3434_167a8f-9d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_167a8f-9d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_167a8f-9d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_167a8f-9d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_167a8f-9d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_167a8f-9d{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_167a8f-9d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_167a8f-9d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_167a8f-9d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_1e7b2f-1f, .wp-block-kadence-advancedheading.kt-adv-heading3434_1e7b2f-1f[data-kb-block=\"kb-adv-heading3434_1e7b2f-1f\"]{text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_1e7b2f-1f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_1e7b2f-1f[data-kb-block=\"kb-adv-heading3434_1e7b2f-1f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_1e7b2f-1f wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_1e7b2f-1f\"><strong>\u57d4\u91cc\u8a08\u7a0b\u8eca\u516c\u53f8<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_f641ee-dd, .wp-block-kadence-advancedheading.kt-adv-heading3434_f641ee-dd[data-kb-block=\"kb-adv-heading3434_f641ee-dd\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_f641ee-dd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_f641ee-dd[data-kb-block=\"kb-adv-heading3434_f641ee-dd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_f641ee-dd wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading3434_f641ee-dd\">\u516c\u5171\u670d\u52d9\uff0c24\u5c0f\u6642\u71df\u696d<br>\u96fb\u8a71: <strong>049-2988414<\/strong><br>\u57d4\u91cc\u8a08\u7a0b\u8eca\u516c\u53f8: <br>\u6295\u7e23\u57d4\u91cc\u93ae\u4e2d\u6b63\u8def336\u865f<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_c2c0f2-1e > .kt-inside-inner-col,.kadence-column3434_c2c0f2-1e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_c2c0f2-1e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_c2c0f2-1e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_c2c0f2-1e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_c2c0f2-1e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_c2c0f2-1e{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_c2c0f2-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_c2c0f2-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_c2c0f2-1e\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3434_086a26-70 > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id3434_086a26-70 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id3434_086a26-70 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3434_086a26-70 > .kt-row-layout-overlay{opacity:0.85;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id3434_086a26-70 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_086a26-70 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_086a26-70 alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom kb-theme-content-width\">\n<style>.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col{display:flex;}.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col,.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_9c9ee2-52{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_9c9ee2-52{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_9c9ee2-52{text-align:left;}.kadence-column3434_9c9ee2-52{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_9c9ee2-52{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_9c9ee2-52{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_9c9ee2-52{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_9c9ee2-52{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_9c9ee2-52 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_9c9ee2-52 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_a21614-48, .wp-block-kadence-advancedheading.kt-adv-heading3434_a21614-48[data-kb-block=\"kb-adv-heading3434_a21614-48\"]{font-size:32px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_a21614-48 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_a21614-48[data-kb-block=\"kb-adv-heading3434_a21614-48\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3434_a21614-48 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading3434_a21614-48\">\u505c\u8eca\u8cc7\u8a0a<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_f8a47b-f3, .wp-block-kadence-advancedheading.kt-adv-heading3434_f8a47b-f3[data-kb-block=\"kb-adv-heading3434_f8a47b-f3\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_f8a47b-f3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_f8a47b-f3[data-kb-block=\"kb-adv-heading3434_f8a47b-f3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_f8a47b-f3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_f8a47b-f3\">\u70ba\u4fdd\u8b77\u81fa\u7063\u7684\u7f8e\u9e97\u74b0\u5883\uff0c\u8acb\u76e1\u91cf\u9078\u64c7\u6211\u5011\u63d0\u4f9b\u7684\u63a5\u99c1\u8eca\u6216\u8207\u670b\u53cb\u5171\u4e58\u3002<br>\u5982\u679c\u5fc5\u9808\u81ea\u884c\u958b\u8eca\uff0c\u8acb\u76e1\u91cf\u8207\u4ed6\u4eba\u5171\u4e58\u4ee5\u6e1b\u5c11\u5c0d\u74b0\u5883\u7684\u5f71\u97ff\u3002<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_446eb2-ed > .kt-inside-inner-col{display:flex;}.kadence-column3434_446eb2-ed > .kt-inside-inner-col,.kadence-column3434_446eb2-ed > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_446eb2-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_446eb2-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_446eb2-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3434_446eb2-ed{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_446eb2-ed{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_446eb2-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_446eb2-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_446eb2-ed{text-align:left;}.kadence-column3434_446eb2-ed{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3434_446eb2-ed{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_446eb2-ed{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_446eb2-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column3434_446eb2-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3434_446eb2-ed{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_446eb2-ed{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3434_446eb2-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column3434_446eb2-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_446eb2-ed kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id3434_3cc03b-f0 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);}.kt-accordion-id3434_3cc03b-f0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:rgba(255,255,255,0);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette7, #EDF2F7);font-size:18px;line-height:1.2;font-weight:600;text-transform:none;color:var(--global-palette3, #1A202C);padding-top:15px;padding-right:20px;padding-bottom:15px;padding-left:0px;}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_3cc03b-f0 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette9, #ffffff);background:var(--global-palette5, #4A5568);border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette1, #3182CE);}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette5, #4A5568);}.kt-accordion-id3434_3cc03b-f0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette9, #ffffff);}.kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3434_3cc03b-f0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.kt-accordion-id3434_3cc03b-f0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;}}@media all and (max-width: 1024px){.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_3cc03b-f0 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 1024px){.kt-accordion-id3434_3cc03b-f0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-accordion-id3434_3cc03b-f0 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3434_3cc03b-f0 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-bottom:2px solid var(--global-palette5, #4A5568);border-left:1px solid;}.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3434_3cc03b-f0 .kt-blocks-accordion-header:focus-visible{border-bottom:1px solid var(--global-palette6, #718096);}.kt-accordion-id3434_3cc03b-f0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3434_3cc03b-f0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-bottom:1px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3434_3cc03b-f0 kt-accordion-has-13-panes kt-active-pane-8 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"true\" data-start-open=\"8\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-9 kt-pane3434_76f241-22\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><strong>\u9031\u4e94 \u505c\u8eca<\/strong><\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column3434_588fe1-95 > .kt-inside-inner-col,.kadence-column3434_588fe1-95 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_588fe1-95 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_588fe1-95 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_588fe1-95 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_588fe1-95 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_588fe1-95{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_588fe1-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_588fe1-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_588fe1-95\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3434_d587a6-43 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3434_d587a6-43 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3434_d587a6-43 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3434_d587a6-43 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_d587a6-43 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3434_d587a6-43 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_d587a6-43 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3434_50431e-2c > .kt-inside-inner-col,.kadence-column3434_50431e-2c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_50431e-2c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_50431e-2c > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_50431e-2c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_50431e-2c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_50431e-2c{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_50431e-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_50431e-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_50431e-2c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_b22346-e5:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_b22346-e5 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_b22346-e5 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_b22346-e5 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_b22346-e5 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_b22346-e5 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_82360e-67 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_82360e-67\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_parking kt-svg-icon-list-single\"><svg viewbox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u4e3b\u8981\u505c\u8eca\u5834\uff1a<\/strong> \u4f4d\u65bc\u9053\u8def\u65c1\uff0c\u6b65\u884c\u7d043\u5206\u9418\u5373\u53ef\u62b5\u9054 YCC\u3002\u505c\u8eca\u4f4d\u50c5\u9650\u65bc\u9732\u71df\u5730\u9644\u8fd1\u9053\u8def\u7684 <strong>\u6cb3\u6ff1\u5c0d\u9762\u5074<\/strong>\u70ba\u4e86\u907f\u514d\u4ea4\u901a\u963b\u585e\uff0c\u8acb\u52ff\u5c07\u8eca\u8f1b\u505c\u5728\u9760\u8fd1\u6cb3\u6ff1\u7684\u90a3\u4e00\u5074\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_b825a3-2a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_b825a3-2a kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_map kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"1 6 1 22 8 18 16 22 23 18 23 2 16 6 8 2 1 6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"18\"\/><line x1=\"16\" y1=\"6\" x2=\"16\" y2=\"22\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/goo.gl\/maps\/Kx563qtzBQx3BW6z8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/goo.gl\/maps\/Kx563qtzBQx3BW6z8<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_19a3ae-19 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_19a3ae-19\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_parking kt-svg-icon-list-single\"><svg viewbox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u9760\u8fd1\u9053\u8def\u7684\u505c\u8eca\u5834\uff1a<\/strong> <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_c698e3-1c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_c698e3-1c kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_map kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"1 6 1 22 8 18 16 22 23 18 23 2 16 6 8 2 1 6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"18\"\/><line x1=\"16\" y1=\"6\" x2=\"16\" y2=\"22\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/maps.app.goo.gl\/uvLwXexZ5x3GbMQ36\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/maps.app.goo.gl\/uvLwXexZ5x3GbMQ36<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_01cb1a-33 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_01cb1a-33\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_parking kt-svg-icon-list-single\"><svg viewbox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u6148\u5b5d\u5802\u9644\u8fd1\uff1a<\/strong> <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_0a7c7f-b3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_0a7c7f-b3 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_map kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"1 6 1 22 8 18 16 22 23 18 23 2 16 6 8 2 1 6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"18\"\/><line x1=\"16\" y1=\"6\" x2=\"16\" y2=\"22\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/maps.app.goo.gl\/1etSH3Y1T2updqjY8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/maps.app.goo.gl\/1etSH3Y1T2updqjY8<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_895aa5-90 > .kt-inside-inner-col,.kadence-column3434_895aa5-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_895aa5-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_895aa5-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_895aa5-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_895aa5-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_895aa5-90{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_895aa5-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_895aa5-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_895aa5-90\"><div class=\"kt-inside-inner-col\"><style>.kb-image3434_4da096-11 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3434_4da096-11 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/09\/FT-parking-along-road.jpg\" alt=\"\" class=\"kb-img wp-image-5522\" srcset=\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/09\/FT-parking-along-road.jpg 1024w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/09\/FT-parking-along-road-300x169.jpg 300w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/09\/FT-parking-along-road-768x433.jpg 768w, https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/09\/FT-parking-along-road-18x10.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_4b54bd-7d:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_4b54bd-7d ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_4b54bd-7d ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_4b54bd-7d ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_4b54bd-7d ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_4b54bd-7d kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_b26428-39 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_b26428-39\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_info kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><line x1=\"12\" y1=\"16\" x2=\"12\" y2=\"12\"\/><line x1=\"12\" y1=\"8\" x2=\"12\" y2=\"8\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u5207\u52ff\u9055\u898f\u505c\u8eca\uff01<\/strong> \u60a8\u7684\u8eca\u8f1b\u5c07\u6703\u88ab\u653f\u5e9c\u55ae\u4f4d\u62d6\u540a\u3002\u8acb\u52d9\u5fc5\u9075\u5b88\u6240\u6709\u4ea4\u901a\u898f\u5247\u3002<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-12 kt-pane3434_51e6d7-07\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong><strong><strong>\u9031\u516d \u505c\u8eca<\/strong><\/strong><\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column3434_99ffe0-4d > .kt-inside-inner-col,.kadence-column3434_99ffe0-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_99ffe0-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_99ffe0-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_99ffe0-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_99ffe0-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_99ffe0-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_99ffe0-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_99ffe0-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_99ffe0-4d\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3434_324c80-36 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3434_324c80-36 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3434_324c80-36 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(80% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id3434_324c80-36 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_324c80-36 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3434_324c80-36 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_324c80-36 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3434_6e9309-28 > .kt-inside-inner-col,.kadence-column3434_6e9309-28 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_6e9309-28 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_6e9309-28 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_6e9309-28 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_6e9309-28 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_6e9309-28{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_6e9309-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_6e9309-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_6e9309-28\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_a15a33-69, .wp-block-kadence-advancedheading.kt-adv-heading3434_a15a33-69[data-kb-block=\"kb-adv-heading3434_a15a33-69\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_a15a33-69 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_a15a33-69[data-kb-block=\"kb-adv-heading3434_a15a33-69\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading3434_a15a33-69 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3434_a15a33-69\">\u9031\u516d\u7684\u505c\u8eca\u4f4d\u6709\u9650\uff0c\u8acb\u8003\u616e\u4ee5\u4e0b\u5730\u9ede\uff0c\u4e26\u9810\u7559\u984d\u5916\u7684\u6b65\u884c\u6642\u9593\u524d\u5f80\u6703\u5834\u3002<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_b57ec0-5a:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_b57ec0-5a ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_b57ec0-5a ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_b57ec0-5a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_b57ec0-5a ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_b57ec0-5a kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_717bf2-31 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_717bf2-31\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_parking kt-svg-icon-list-single\"><svg viewbox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u9760\u8fd1\u9053\u8def\u7684\u505c\u8eca\u5834\uff1a<\/strong> \u5efa\u8b70 <strong>104\u300175\u300140\u516c\u91cc\u7d44<\/strong> \u53c3\u8cfd\u8005\u512a\u5148\u4f7f\u7528\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_779959-32 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_779959-32 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_map kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"1 6 1 22 8 18 16 22 23 18 23 2 16 6 8 2 1 6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"18\"\/><line x1=\"16\" y1=\"6\" x2=\"16\" y2=\"22\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/maps.app.goo.gl\/uvLwXexZ5x3GbMQ36\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/maps.app.goo.gl\/uvLwXexZ5x3GbMQ36<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_a6ff0f-4b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_a6ff0f-4b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_parking kt-svg-icon-list-single\"><svg viewbox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u6148\u5b5d\u5802\u9644\u8fd1\uff1a<\/strong> \u5efa\u8b70 <strong>18\u300110\u516c\u91cc\u7d44<\/strong> \u53c3\u8cfd\u8005\u512a\u5148\u4f7f\u7528\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_abd45d-a7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_abd45d-a7 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_map kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"1 6 1 22 8 18 16 22 23 18 23 2 16 6 8 2 1 6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"18\"\/><line x1=\"16\" y1=\"6\" x2=\"16\" y2=\"22\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/maps.app.goo.gl\/1etSH3Y1T2updqjY8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/maps.app.goo.gl\/1etSH3Y1T2updqjY8<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_2bdf2e-0f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_2bdf2e-0f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_parking kt-svg-icon-list-single\"><svg viewbox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u9bc9\u9b5a\u6f6d\u9644\u8fd1\uff1a<\/strong> \u6b65\u884c\u7d04 1.4\u516c\u91cc\u3002\u4e0d\u4fdd\u8b49\u6709\u8eca\u4f4d\uff0c\u4e3b\u8981\u4f9b\u6e56\u7554\u98ef\u5e97\u4f4f\u5bbf\u8005\u4f7f\u7528\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_83bd28-46 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_83bd28-46 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_map kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"1 6 1 22 8 18 16 22 23 18 23 2 16 6 8 2 1 6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"18\"\/><line x1=\"16\" y1=\"6\" x2=\"16\" y2=\"22\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/maps.app.goo.gl\/bEmJ7bgu7EfiXZCB9\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/maps.app.goo.gl\/bEmJ7bgu7EfiXZCB9<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_4c2c0e-b9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_4c2c0e-b9\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_parking kt-svg-icon-list-single\"><svg viewbox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u8b1d\u7def\u7d00\u5ff5\u71df\u5730\u9644\u8fd1\u8f03\u5c0f\u505c\u8eca\u5834\uff1a<\/strong> \u6b65\u884c\u7d04 1.7\u516c\u91cc\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_5f15a6-47 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_5f15a6-47 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_map kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"1 6 1 22 8 18 16 22 23 18 23 2 16 6 8 2 1 6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"18\"\/><line x1=\"16\" y1=\"6\" x2=\"16\" y2=\"22\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/maps.app.goo.gl\/9LKiHY66Lbr7BaFc7r7BaFc7\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/maps.app.goo.gl\/9LKiHY66Lbr7BaFc7r7BaFc7<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_71fe50-c8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_71fe50-c8\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_parking kt-svg-icon-list-single\"><svg viewbox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u79c1\u4eba\u571f\u5730\uff1a<\/strong> \u6b65\u884c\u7d04 2.2\u516c\u91cc\u3002\u6b64\u8655\u82e5\u78ba\u5b9a\u53ef\u4f9b\u505c\u8eca\uff0c\u5c07\u6703\u53e6\u884c\u516c\u544a\u3002<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_1dc09f-4011 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_1dc09f-4011 kt-svg-icon-list-level-1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_map kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polygon points=\"1 6 1 22 8 18 16 22 23 18 23 2 16 6 8 2 1 6\"\/><line x1=\"8\" y1=\"2\" x2=\"8\" y2=\"18\"\/><line x1=\"16\" y1=\"6\" x2=\"16\" y2=\"22\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/maps.app.goo.gl\/TqBbNzopQUxUsRJy6\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/maps.app.goo.gl\/TqBbNzopQUxUsRJy6<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3434_6768bc-5d > .kt-inside-inner-col,.kadence-column3434_6768bc-5d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_6768bc-5d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_6768bc-5d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_6768bc-5d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_6768bc-5d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_6768bc-5d{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_6768bc-5d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_6768bc-5d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_6768bc-5d\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3434_6d6d1a-ab > .kt-inside-inner-col,.kadence-column3434_6d6d1a-ab > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_6d6d1a-ab > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_6d6d1a-ab > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_6d6d1a-ab > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_6d6d1a-ab > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_6d6d1a-ab{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_6d6d1a-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_6d6d1a-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_6d6d1a-ab\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_c99270-02:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_c99270-02 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_c99270-02 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3434_c99270-02 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3434_c99270-02 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3434_c99270-02 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3434_d81d7c-9a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_d81d7c-9a\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_info kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><line x1=\"12\" y1=\"16\" x2=\"12\" y2=\"12\"\/><line x1=\"12\" y1=\"8\" x2=\"12\" y2=\"8\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><em>\u90e8\u5206\u505c\u8eca\u5834\u53ef\u80fd\u7531\u5730\u4e3b\u6536\u8cbb\uff0c\u6bcf\u53f0\u8eca\u7d04 <\/em><strong><em>\u65b0\u53f0\u5e63 100\u5143\u3002<\/em><\/strong><em>\u8eca\u4f4d\u6578\u91cf\u6709\u9650\u3002<\/em><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3434_ebdc76-69 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3434_ebdc76-69\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_info kt-svg-icon-list-single\"><svg viewbox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><line x1=\"12\" y1=\"16\" x2=\"12\" y2=\"12\"\/><line x1=\"12\" y1=\"8\" x2=\"12\" y2=\"8\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><strong>\u5207\u52ff\u9055\u898f\u505c\u8eca\uff01<\/strong> \u60a8\u7684\u8eca\u8f1b\u5c07\u6703\u88ab\u653f\u5e9c\u55ae\u4f4d\u62d6\u540a\u3002\u8acb\u52d9\u5fc5\u9075\u5b88\u6240\u6709\u4ea4\u901a\u898f\u5247\u3002<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3434_6fba15-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3434_6fba15-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3434_6fba15-d2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3434_6fba15-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3434_6fba15-d2 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-sm, 1rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3434_6fba15-d2 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-sm, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3434_6fba15-d2 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3434_d85bd1-f9 > .kt-inside-inner-col,.kadence-column3434_d85bd1-f9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_d85bd1-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_d85bd1-f9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_d85bd1-f9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_d85bd1-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_d85bd1-f9{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_d85bd1-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_d85bd1-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_d85bd1-f9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3434_5a6d44-74, .wp-block-kadence-advancedheading.kt-adv-heading3434_5a6d44-74[data-kb-block=\"kb-adv-heading3434_5a6d44-74\"]{padding-bottom:var(--global-kb-spacing-md, 2rem);margin-bottom:0px;font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_5a6d44-74 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_5a6d44-74[data-kb-block=\"kb-adv-heading3434_5a6d44-74\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3434_5a6d44-74 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading3434_5a6d44-74\">\u5f9e\u5176\u4ed6\u5730\u65b9\u4f86\u55ce\uff1f<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3434_d9b575-a2, .wp-block-kadence-advancedheading.kt-adv-heading3434_d9b575-a2[data-kb-block=\"kb-adv-heading3434_d9b575-a2\"]{padding-bottom:var(--global-kb-spacing-md, 2rem);margin-bottom:0px;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3434_d9b575-a2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3434_d9b575-a2[data-kb-block=\"kb-adv-heading3434_d9b575-a2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3434_d9b575-a2 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3434_d9b575-a2\">\u8b93\u6211\u5011\u4e86\u89e3<\/h2>\n\n\n<style>.kadence-form-3434_01feef-ef .kb-form .kadence-blocks-form-field{margin-bottom:24px;}.kadence-form-3434_01feef-ef .kb-form .kadence-blocks-form-field{padding-right:12px;padding-left:12px;}.kadence-form-3434_01feef-ef .kb-form{margin-right:-12px;margin-left:-12px;}.kadence-form-3434_01feef-ef .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-3434_01feef-ef .kb-form .kadence-blocks-form-field .kb-select-style-field{border-radius:0px;font-size:var(--global-kb-font-size-sm, 0.9rem);border-width:0px 0px 1px 0px;background:rgba(255, 255, 255, 0);border-color:var(--global-palette6, #718096);}.kadence-form-3434_01feef-ef .kb-form .kadence-blocks-form-field > label{font-size:var(--global-kb-font-size-sm, 0.9rem);text-transform:uppercase;}.kadence-form-3434_01feef-ef .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);border-radius:0px;border-width:1px 1px 1px 1px;background:var(--global-palette1, #3182CE);}.kadence-form-3434_01feef-ef .kb-form .kadence-blocks-form-field .kb-forms-submit{margin-top:0%;margin-right:0%;margin-bottom:0%;margin-left:0%;}.kadence-form-3434_01feef-ef .kb-form .kadence-blocks-form-field .kb-forms-submit{font-size:var(--global-kb-font-size-md, 1.25rem);}.kadence-form-3434_01feef-ef .kadence-blocks-form-warning{color:#e46565;border-color:rgba(0,0,0,0);background:rgba(0, 0, 0, 0);}.kadence-form-3434_01feef-ef .kadence-blocks-form-message, .kadence-form-3434_01feef-ef .kb-form-error-msg{font-size:var(--global-kb-font-size-sm, 0.9rem);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-3434_01feef-ef kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-trp-original-action=\"\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_3434_01feef-ef_0\">\u5168\u540d<span class=\"required\">*<\/span><\/label><input name=\"kb_field_0\" id=\"kb_field_3434_01feef-ef_0\" data-label=\"Full Name\" type=\"text\" placeholder=\"Enter your name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_3434_01feef-ef_1\">\u5831\u540dID<\/label><input name=\"kb_field_1\" id=\"kb_field_3434_01feef-ef_1\" data-label=\"Registration ID #\" type=\"text\" placeholder=\"Already regsitered? Input your Registration ID\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-1\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_3434_01feef-ef_2\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_3434_01feef-ef_2\" data-label=\"Email\" type=\"email\" placeholder=\"Enter your email\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_3434_01feef-ef_3\">\u7d66\u4e3b\u8fa6\u55ae\u4f4d\u7684\u8a0a\u606f<span class=\"required\">*<\/span><\/label><textarea name=\"kb_field_3\" id=\"kb_field_3434_01feef-ef_3\" data-label=\"Message to Organizers\" type=\"textarea\" placeholder=\"Enter your message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"3\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"3434_01feef-ef\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"3434\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><input type=\"hidden\" name=\"recaptcha_response\" class=\"kb_recaptcha_response kb_recaptcha_3434_01feef-ef\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\">\u767c\u9001\u60a8\u7684\u8a0a\u606f<\/button><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"zh\"\/><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-3434_01feef-ef .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n\n\n<style>.kadence-column3434_5408a5-33 > .kt-inside-inner-col,.kadence-column3434_5408a5-33 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3434_5408a5-33 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3434_5408a5-33 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3434_5408a5-33 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3434_5408a5-33 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3434_5408a5-33{position:relative;}@media all and (max-width: 1024px){.kadence-column3434_5408a5-33 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3434_5408a5-33 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3434_5408a5-33 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-google-maps-container3434_702e7a-71{height:600px;}.kb-google-maps-container3434_702e7a-71{filter:sepia(30%);}<\/style><div class=\"kb-google-maps-container kb-google-maps-container3434_702e7a-71  wp-block-kadence-googlemaps\" data-mapid=\"3434_702e7a71\"><iframe width=\"100%\" height=\"100%\"\n\t\t\t\t\t\t\tstyle=\"border:0\" loading=\"lazy\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBAM2o7PiQqwk15LC1XRH2e_KJ-jUa7KYk&#038;zoom=13&#038;maptype=roadmap&#038;q=Puli+bus+station\"\n\t\t\t\t\t\t\ttitle=\"Google map of Puli bus station\"><\/iframe><\/div><script>function kb_google_map3434_702e7a71() { let center = { lat: 37.8201, lng: -122.4781}; let map = new google.maps.Map(document.getElementById(\"kb-google-map3434_702e7a71\"), {\n\t\t\t\t\t    zoom: 13,\n\t\t\t\t\t    center: center,});let marker = new google.maps.Marker({   position: { lat: 37.8201, lng: -122.4781},    map: map,  });}<\/script><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>TRANSPORTATION Be Green \u2013 Take bus \ud83d\ude8c\ud83c\udf3f We took care about everything! Three days in Central Taiwan &#8211; Puli. WAYS TO COME Airports TAXI PARKING Please choose our shuttle buses or carpool with friends to reduce traffic and emissions.If you must drive, please share your car with others to help us protect the environment. COMING&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-3434","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transportation - FORMOSA TRAIL<\/title>\n<meta name=\"description\" content=\"Transportation. Be Green \u2013 Take bus. We took care about everything! Book shuttle bus during registration. Bus from Taipei..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/formosatrail.com\/zh\/transportation\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transportation - FORMOSA TRAIL\" \/>\n<meta property=\"og:description\" content=\"Transportation. Be Green \u2013 Take bus. We took care about everything! Book shuttle bus during registration. Bus from Taipei..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/formosatrail.com\/zh\/transportation\/\" \/>\n<meta property=\"og:site_name\" content=\"FORMOSA TRAIL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BeastRunners?locale=zh_TW\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T22:14:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9810\u4f30\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/formosatrail.com\/transportation\/\",\"url\":\"https:\/\/formosatrail.com\/transportation\/\",\"name\":\"Transportation - FORMOSA TRAIL\",\"isPartOf\":{\"@id\":\"https:\/\/formosatrail.com\/zh\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/formosatrail.com\/transportation\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/formosatrail.com\/transportation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-683x1024.jpg\",\"datePublished\":\"2025-03-30T08:12:42+00:00\",\"dateModified\":\"2026-04-20T22:14:28+00:00\",\"description\":\"Transportation. Be Green \u2013 Take bus. We took care about everything! Book shuttle bus during registration. Bus from Taipei..\",\"breadcrumb\":{\"@id\":\"https:\/\/formosatrail.com\/transportation\/#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/formosatrail.com\/transportation\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\/\/formosatrail.com\/transportation\/#primaryimage\",\"url\":\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-683x1024.jpg\",\"contentUrl\":\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-683x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/formosatrail.com\/transportation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/formosatrail.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transportation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/formosatrail.com\/zh\/#website\",\"url\":\"https:\/\/formosatrail.com\/zh\/\",\"name\":\"FORMOSA TRAIL\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/formosatrail.com\/zh\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/formosatrail.com\/zh\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/formosatrail.com\/zh\/#organization\",\"name\":\"FORMOSA TRAIL\",\"alternateName\":\"FT\",\"url\":\"https:\/\/formosatrail.com\/zh\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\/\/formosatrail.com\/zh\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/FT-diamond-new-color.webp\",\"contentUrl\":\"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/FT-diamond-new-color.webp\",\"width\":150,\"height\":150,\"caption\":\"FORMOSA TRAIL\"},\"image\":{\"@id\":\"https:\/\/formosatrail.com\/zh\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/BeastRunners?locale=zh_TW\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transportation - FORMOSA TRAIL","description":"Transportation. Be Green \u2013 Take bus. We took care about everything! Book shuttle bus during registration. Bus from Taipei..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/formosatrail.com\/zh\/transportation\/","og_locale":"zh_TW","og_type":"article","og_title":"Transportation - FORMOSA TRAIL","og_description":"Transportation. Be Green \u2013 Take bus. We took care about everything! Book shuttle bus during registration. Bus from Taipei..","og_url":"https:\/\/formosatrail.com\/zh\/transportation\/","og_site_name":"FORMOSA TRAIL","article_publisher":"https:\/\/www.facebook.com\/BeastRunners?locale=zh_TW","article_modified_time":"2026-04-20T22:14:28+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u9810\u4f30\u95b1\u8b80\u6642\u9593":"6 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/formosatrail.com\/transportation\/","url":"https:\/\/formosatrail.com\/transportation\/","name":"Transportation - FORMOSA TRAIL","isPartOf":{"@id":"https:\/\/formosatrail.com\/zh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/formosatrail.com\/transportation\/#primaryimage"},"image":{"@id":"https:\/\/formosatrail.com\/transportation\/#primaryimage"},"thumbnailUrl":"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-683x1024.jpg","datePublished":"2025-03-30T08:12:42+00:00","dateModified":"2026-04-20T22:14:28+00:00","description":"Transportation. Be Green \u2013 Take bus. We took care about everything! Book shuttle bus during registration. Bus from Taipei..","breadcrumb":{"@id":"https:\/\/formosatrail.com\/transportation\/#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/formosatrail.com\/transportation\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/formosatrail.com\/transportation\/#primaryimage","url":"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-683x1024.jpg","contentUrl":"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/dynamic-cityscape-with-a-red-bus-in-motion-set-against-a-modern-building-facade.-2085503-683x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/formosatrail.com\/transportation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/formosatrail.com\/"},{"@type":"ListItem","position":2,"name":"Transportation"}]},{"@type":"WebSite","@id":"https:\/\/formosatrail.com\/zh\/#website","url":"https:\/\/formosatrail.com\/zh\/","name":"FORMOSA TRAIL","description":"","publisher":{"@id":"https:\/\/formosatrail.com\/zh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/formosatrail.com\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/formosatrail.com\/zh\/#organization","name":"FORMOSA TRAIL","alternateName":"FT","url":"https:\/\/formosatrail.com\/zh\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/formosatrail.com\/zh\/#\/schema\/logo\/image\/","url":"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/FT-diamond-new-color.webp","contentUrl":"https:\/\/formosatrail.com\/wp-content\/uploads\/2025\/03\/FT-diamond-new-color.webp","width":150,"height":150,"caption":"FORMOSA TRAIL"},"image":{"@id":"https:\/\/formosatrail.com\/zh\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BeastRunners?locale=zh_TW"]}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Beast Runners \u8dd1\u5c71\u7378","author_link":"https:\/\/formosatrail.com\/zh\/article\/author\/beast_47hgwj\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/formosatrail.com\/zh\/wp-json\/wp\/v2\/pages\/3434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/formosatrail.com\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/formosatrail.com\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/formosatrail.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/formosatrail.com\/zh\/wp-json\/wp\/v2\/comments?post=3434"}],"version-history":[{"count":10,"href":"https:\/\/formosatrail.com\/zh\/wp-json\/wp\/v2\/pages\/3434\/revisions"}],"predecessor-version":[{"id":6032,"href":"https:\/\/formosatrail.com\/zh\/wp-json\/wp\/v2\/pages\/3434\/revisions\/6032"}],"wp:attachment":[{"href":"https:\/\/formosatrail.com\/zh\/wp-json\/wp\/v2\/media?parent=3434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}